{"id":2603,"date":"2017-09-19T08:39:13","date_gmt":"2017-09-19T06:39:13","guid":{"rendered":"https:\/\/pre.lavillarroel.cat\/ex\/\/oswaldo-digon-dialogos-en-3d-2\/"},"modified":"2017-09-19T08:39:13","modified_gmt":"2017-09-19T06:39:13","slug":"oswaldo-digon-dialogos-en-3d-2","status":"publish","type":"ex","link":"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/","title":{"rendered":"Oswaldo Dig\u00f3n. Di\u00e1logos en 3D"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","class_list":["post-2603","ex","type-ex","status-publish","hentry","season-2013-14"],"acf":{"txt_synopsis":"<p>\"La por t\u00e9 una estructura narrativa, per aix\u00f2 cal descriure-la explicant hist\u00f2ries\". <strong>J.A. Marina<\/strong>.<br \/><br \/><strong>Oswaldo Dig\u00f3n<\/strong> ens mostra els seus <strong>pitjors temors<\/strong> a trav\u00e9s <strong>d'hist\u00f2ries plenes d'humor<\/strong>, tendresa i girs inesperats:&nbsp;\"Faig com\u00e8dia per qu\u00e8 no s\u00e9 resar de cap altra manera\".<\/p>\n<p>Rebem l'Oswaldo a l'andana d'una estaci\u00f3 de tren. El motiu del seu viatge&nbsp;\u00e9s un assumpte important. A poc a poc ens va revelant quina \u00e9s el seu pitjor temor i per combatre'l s'inventa suposades hist\u00f2ries&nbsp;sobre els seus companys de viatge.<\/p>\n<p>Qui no ha jugat mai a inventar-se la vida de&nbsp;persones desconegudes que veiem mentre esperem a aquella parella impuntual, o mentre fem temps a la sala d'espera, o mentre viatgem en metro? L'Oswaldo ens explica aquestes hist\u00f2ries per\u00f2 sobre tot ens explica quin \u00e9s l'aut\u00e8ntic motiu del seu viatge. Vols saber qui \u00e9s?<\/p>\n<p>Despr\u00e9s de veure aquest espectacle potser coneixereu a aquest actor gallec, per\u00f2 segur que us haureu divertit, rigut i emocionat amb els seus <strong>DI\u00c1LOGOS EN 3D<\/strong>.<\/p>","main_buy_link":"#","main_buy_links":"","group_buy_link":"","show_language":"","show_duration":"","show_start_date":"20131004000000","show_end_date":"20140627000000","show_sort_date":"20131101000000","txt_custom_show_dates":"del 4 d'octubre de 2013 al 27 de juny de 2014","show_disciplines":"","show_ultimes_funcions":false,"hide_tarifes_especials":false,"show_properament":false,"txt_additional_info":"","txt_present":"","show_season":[60],"txt_season":"[\"2013\/14\"]","txt_cycle":"","txt_claim":"","txt_cast_excerpt":"","txt_cast":"","txt_reviews":"","hashtag":"","have_promo":"","slogan":"","id_exhibicio":913,"id_versio":631,"id_local":4,"txt_seo_desc":"","data_images":"[{\"localizer\":\"V2EXHBCARTELL\",\"url\":\"media\/ver\/cartell\/3125D\/01_079_00026606\/list.jpg\",\"thumb_url\":\"media\/ver\/cartell\/3125D\/01_079_00026606\/list_thumb.jpg\",\"title\":\"Di\u00e1logos en 3D\",\"description\":\"Di\u00e1logos en 3D\",\"copyright\":\"\",\"order\":1},{\"localizer\":\"V2SLIDE\",\"url\":\"media\/ftgalslide\/31255\/01_076_00023830\/slide02.jpg\",\"thumb_url\":\"media\/ftgalslide\/31255\/01_076_00023830\/slide02_thumb.jpg\",\"title\":\"Di\u00e1logos en 3D\",\"description\":\"Oswaldo Dig\u00f3n\",\"copyright\":\"http:\/\/www.youtube.com\/watch?v=t2nTvhDFxH4\",\"order\":3},{\"localizer\":\"V2EXHBCARTELL\",\"url\":\"media\/ver\/cartell\/312C2\/01_079_00031403\/Focus_Barcelona_Dialogosen3D_300x427.jpg\",\"thumb_url\":\"media\/ver\/cartell\/312C2\/01_079_00031403\/Focus_Barcelona_Dialogosen3D_300x427_thumb.jpg\",\"title\":\"Oswaldo Dig\u00f3n\",\"description\":\"Oswaldo Dig\u00f3n\",\"copyright\":\"\",\"order\":5},{\"localizer\":\"V2PORTADA\",\"url\":\"media\/ver\/port\/31383\/01_078_00036648\/Focus_DIALOGOSEN3D_581x327.jpg\",\"thumb_url\":\"media\/ver\/port\/31383\/01_078_00036648\/Focus_DIALOGOSEN3D_581x327_thumb.jpg\",\"title\":\"Oswaldo\",\"description\":\"Oswaldo\",\"copyright\":\"\",\"order\":6},{\"localizer\":\"V2CARTELL\",\"url\":\"media\/ver\/cartell\/31383\/01_079_00036649\/Focus_DIALOGOSEN3D_300x427.jpg\",\"thumb_url\":\"media\/ver\/cartell\/31383\/01_079_00036649\/Focus_DIALOGOSEN3D_300x427_thumb.jpg\",\"title\":\"Oswaldo\",\"description\":\"Oswaldo\",\"copyright\":\"\",\"order\":7}]","material__texto_intro":"","data_material":null,"data_gallery":"","data_discounts":"[]","contract_is_open":false,"in_tour":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oswaldo Dig\u00f3n. Di\u00e1logos en 3D - La Villarroel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/ex\\\/oswaldo-digon-dialogos-en-3d-2\\\/\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/ex\\\/oswaldo-digon-dialogos-en-3d-2\\\/\",\"name\":\"Oswaldo Dig\u00f3n. Di\u00e1logos en 3D - La Villarroel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/#website\"},\"datePublished\":\"2017-09-19T06:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/ex\\\/oswaldo-digon-dialogos-en-3d-2\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/ex\\\/oswaldo-digon-dialogos-en-3d-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/ex\\\/oswaldo-digon-dialogos-en-3d-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espectacles\",\"item\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/ex\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oswaldo Dig\u00f3n. Di\u00e1logos en 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/\",\"name\":\"La Villarroel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/#organization\",\"name\":\"La Villarroel\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/09\\\/teatre-villaroel-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.lavillarroel.cat\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/09\\\/teatre-villaroel-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"La Villarroel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/TeatreVillarroel\",\"https:\\\/\\\/x.com\\\/la_villarroel\",\"http:\\\/\\\/instagram.com\\\/la_villarroel\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/LaVillarroel#p\\\/u\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oswaldo Dig\u00f3n. Di\u00e1logos en 3D - La Villarroel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/","url":"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/","name":"Oswaldo Dig\u00f3n. Di\u00e1logos en 3D - La Villarroel","isPartOf":{"@id":"https:\/\/www.lavillarroel.cat\/ca\/#website"},"datePublished":"2017-09-19T06:39:13+00:00","breadcrumb":{"@id":"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lavillarroel.cat\/ca\/ex\/oswaldo-digon-dialogos-en-3d-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.lavillarroel.cat\/ca\/"},{"@type":"ListItem","position":2,"name":"Espectacles","item":"https:\/\/www.lavillarroel.cat\/ca\/ex\/"},{"@type":"ListItem","position":3,"name":"Oswaldo Dig\u00f3n. Di\u00e1logos en 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.lavillarroel.cat\/ca\/#website","url":"https:\/\/www.lavillarroel.cat\/ca\/","name":"La Villarroel","description":"","publisher":{"@id":"https:\/\/www.lavillarroel.cat\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lavillarroel.cat\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.lavillarroel.cat\/ca\/#organization","name":"La Villarroel","url":"https:\/\/www.lavillarroel.cat\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.lavillarroel.cat\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.lavillarroel.cat\/wp-content\/uploads\/sites\/5\/2017\/09\/teatre-villaroel-logo.svg","contentUrl":"https:\/\/www.lavillarroel.cat\/wp-content\/uploads\/sites\/5\/2017\/09\/teatre-villaroel-logo.svg","width":1,"height":1,"caption":"La Villarroel"},"image":{"@id":"https:\/\/www.lavillarroel.cat\/ca\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/TeatreVillarroel","https:\/\/x.com\/la_villarroel","http:\/\/instagram.com\/la_villarroel","http:\/\/www.youtube.com\/user\/LaVillarroel#p\/u"]}]}},"translations":[{"id":2603,"locale":"ca"},{"id":2808,"locale":"es"}],"_links":{"self":[{"href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/ex\/2603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/ex"}],"about":[{"href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/types\/ex"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/comments?post=2603"}],"acf:term":[{"embeddable":true,"taxonomy":"season","href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/season\/60"}],"wp:attachment":[{"href":"https:\/\/www.lavillarroel.cat\/ca\/wp-json\/wp\/v2\/media?parent=2603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}