{"id":3265,"date":"2023-06-01T15:51:21","date_gmt":"2023-06-01T13:51:21","guid":{"rendered":"https:\/\/www.lavillarroel.cat\/ex\/loreneta-3\/"},"modified":"2024-05-14T11:19:18","modified_gmt":"2024-05-14T09:19:18","slug":"loreneta","status":"publish","type":"ex","link":"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/","title":{"rendered":"L&#8217;Oreneta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-3265","ex","type-ex","status-publish","hentry","season-2021-22"],"acf":{"txt_synopsis":"La se\u00f1ora Am\u00e8lia, una profesora de canto, recibe en su casa a un hombre joven que quiere mejorar su t\u00e9cnica vocal para cantar en el memorial de su madre fallecida recientemente. Pronto descubrimos que la canci\u00f3n elegida, \u201cL\u2019Oreneta\u201d, tiene un significado especial para los dos personajes, que ir\u00e1n desgranando detalles de su pasado, marcado por un atentado terrorista de signo islamista que sufri\u00f3 la ciudad el a\u00f1o anterior.","main_buy_link":"","main_buy_links":"","group_buy_link":"","show_language":"Espect\u00e1culo en catal\u00e1n","show_duration":"90","show_start_date":"20220218000000","show_end_date":"20220501000000","show_sort_date":"20220218000000","txt_custom_show_dates":"del 18 de febrero al 1 de mayo de 2022 ","show_disciplines":"11","show_ultimes_funcions":false,"hide_tarifes_especials":false,"show_properament":false,"txt_additional_info":"<p><i class=\"fa fa-deaf fa-2x fa-fw\"><\/i>Funci\u00f3n accesible: 15 de abril a las 20:00h <\/p>\r\n<p>La funci\u00f3n contar\u00e1 con:<br \/>\u00b7 Audiodescripci\u00f3n<br \/>\u00b7 Subtitulado<br \/>\u00b7 Bucle magn\u00e9tico individual<br \/>\u00b7 Sonido amplificado con auriculares<\/p>\r\n<p><i class=\"fa fa-info fa-2x fa-fw\"><\/i>El d\u00eda 26 de abril se celebrar\u00e1 una postfunci\u00f3n en colaboraci\u00f3n con \u00d2mnium cultural y la presencia de su director Josep Maria Mestres, y su autor, Guillem Clua. Moderar\u00e1 el coloquio el periodista de La Vanguardia Pere Sol\u00e0 Gimferrer.<\/p>","txt_present":"","show_season":[93],"txt_season":"[\"2021\/22\"]","txt_cycle":"","txt_claim":"La se\u00f1ora Am\u00e8lia, una profesora de canto, recibe en su casa a un hombre joven que quiere mejorar su t\u00e9cnica vocal para cantar en el memorial de su madre fallecida recientemente. Pronto descubrimos que la canci\u00f3n elegida, \u201cL\u2019Oreneta\u201d, tiene un significado especial para los dos personajes","txt_cast_excerpt":"","txt_cast":"<p>Autor: <strong>Guillem Clua<br \/><\/strong>Direcci\u00f3n: <strong>Josep Maria Mestres<\/strong><\/p>\r\n<p>Interpretes:<br \/><strong>Emma Vilarasau<br \/>Dafnis Balduz<\/strong><\/p>\r\n<p>Escenograf\u00eda:&nbsp; <strong>Alessio Meloni<br \/><\/strong>Vestuario: <strong>N\u00eddia Tusal <br \/><\/strong>Iluminaci\u00f3n:&nbsp; <strong>Ignasi Camprodon <br \/><\/strong>Caracterizaci\u00f3n: <strong>N\u00faria Llunell<br \/><\/strong>Ayudant\u00eda de direcci\u00f3n: <strong>Carol Ibarz <\/strong><\/p>\r\n<p>Direcci\u00f3n de producci\u00f3n: <strong>Maite Pijuan<br \/><\/strong>Jefa de producci\u00f3n: <strong>Marina Vilardell<br \/><\/strong>Producci\u00f3n ejecutiva: <strong>Raquel Do\u00f1oro, Alvar Rovira<br \/><\/strong>Direcci\u00f3n de oficina t\u00e9cnica: <strong>Moi Cuenca<br \/><\/strong>Oficina t\u00e9cnica: <strong>David Ruiz<\/strong><\/p>\r\n<p>Regidor\u00eda: <strong>Vicen\u00e7 Beltran<\/strong><\/p>\r\n<p>Jefe t\u00e9cnico del Teatro: <strong>Iker Gabald\u00f3n <\/strong><\/p>\r\n<p>Construcci\u00f3n de la escenograf\u00eda:&nbsp; <strong>Jorba-Mir\u00f3 Estudi-Taller d\u2019escenografia<\/strong><\/p>\r\n<p>Prensa: <strong>Albert L\u00f3pez y Judit Hern\u00e1ndez<br \/><\/strong>M\u00e1rquetin y comunicaci\u00f3n: <strong>Publispec<\/strong><br \/>Dise\u00f1o gr\u00e1fico: <strong>Santi&Kco<br \/><\/strong>Reportaje Fotogr\u00e1fico: <strong>David Ruano<\/strong><\/p>\r\n<p><em>L\u2019Oreneta<\/em> es una canci\u00f3n&nbsp; original de <strong>I\u00f1aki Salvador<\/strong><\/p>\r\n<p>Agradecimientos: <strong>Dolors Aldea, Ignacio Mateos<\/strong><\/p>\r\n<p>Es una coproducci\u00f3n de: <strong>Focus, LA Zona y Un 9 Teatre a l\u2019Est<\/strong><\/p>\r\n<p>Colaboradores: <strong>Jorge de La Garza, Montibello, Rowenta, Blanca Tor\u00e0 Micheli&nbsp; <\/strong><\/p>","txt_reviews":"Pep Vila|Recomana.cat|\"Contundent i commovedora\"\r\nManuel P\u00e9rez|El Peri\u00f3dico|\u201cMec\u00e0nica argumental, enginyeria del drama que funciona amb la precisi\u00f3 d\u2019un rellotge constru\u00eft amb artesania i intu\u00efci\u00f3.\u201d","hashtag":"LOreneta","have_promo":"","slogan":"","id_exhibicio":1850,"id_versio":1478,"id_local":4,"txt_seo_desc":"Emma Vilarasau y Dafnis Balduz protagonizan L'Oreneta en La Villarroel de Barcelona","data_images":"[{\"localizer\":\"V3CARTELL\",\"url\":\"media\/ver\/cartell\/v3\/3157E\/01_085_00051947\/cartell-web-loreneta-la-villarroel-teatre.jpg\",\"thumb_url\":\"media\/ver\/cartell\/v3\/3157E\/01_085_00051947\/cartell-web-loreneta-la-villarroel-teatre_thumb.jpg\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"loreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":5},{\"localizer\":\"V3SLIDE\",\"url\":\"media\/ftgalslide\/v3\/315DA\/01_086_00053302\/T22_Loreneta_045.jpg\",\"thumb_url\":\"media\/ftgalslide\/v3\/315DA\/01_086_00053302\/T22_Loreneta_045_thumb.jpg\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"loreneta a la villarroel de barcelona\",\"copyright\":\"https:\/\/www.youtube.com\/watch?v=to_0IWaPrUA\",\"order\":8},{\"localizer\":\"V3SLIDE\",\"url\":\"media\/ftgalslide\/v3\/315DA\/01_086_00053303\/T22_Loreneta_086.jpg\",\"thumb_url\":\"media\/ftgalslide\/v3\/315DA\/01_086_00053303\/T22_Loreneta_086_thumb.jpg\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"loreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":9},{\"localizer\":\"V3SLIDE\",\"url\":\"media\/ftgalslide\/v3\/315DA\/01_086_00053304\/T22_Loreneta_059.jpg\",\"thumb_url\":\"media\/ftgalslide\/v3\/315DA\/01_086_00053304\/T22_Loreneta_059_thumb.jpg\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"loreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":10},{\"localizer\":\"V3SLIDE\",\"url\":\"media\/ftgalslide\/v3\/315DB\/01_086_00053527\/T22_Loreneta_II_117.jpg\",\"thumb_url\":\"media\/ftgalslide\/v3\/315DB\/01_086_00053527\/T22_Loreneta_II_117_thumb.jpg\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"loreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":11},{\"localizer\":\"V3EXHBCARTELL\",\"url\":\"media\/ver\/cartell\/v3\/315E0\/01_085_00054576\/Cartell-web-loreneta-teatre-la-villarroel.jpg\",\"thumb_url\":\"media\/ver\/cartell\/v3\/315E0\/01_085_00054576\/Cartell-web-loreneta-teatre-la-villarroel_thumb.jpg\",\"title\":\"L'oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":15},{\"localizer\":\"V3EXHBCARTELL\",\"url\":\"media\/ver\/cartell\/v3\/315E0\/01_085_00054577\/Cartell-web-loreneta-teatre-la-villarroel.jpg\",\"thumb_url\":\"media\/ver\/cartell\/v3\/315E0\/01_085_00054577\/Cartell-web-loreneta-teatre-la-villarroel_thumb.jpg\",\"title\":\"L'oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":16},{\"localizer\":\"V3PORTADA\",\"url\":\"media\/ver\/port\/v3\/315E0\/01_084_00054579\/Portada-1-loreneta-teatre-la-villarroel.jpg\",\"thumb_url\":\"media\/ver\/port\/v3\/315E0\/01_084_00054579\/Portada-1-loreneta-teatre-la-villarroel_thumb.jpg\",\"title\":\"L'oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":17},{\"localizer\":\"V3PORTADAWIDE\",\"url\":\"media\/ver\/port\/v3wide\/31640\/01_088_00055905\/PORTADA-0.jpg\",\"thumb_url\":\"media\/ver\/port\/v3wide\/31640\/01_088_00055905\/PORTADA-0_thumb.jpg\",\"title\":\"L'oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel\",\"copyright\":\"\",\"order\":18},{\"localizer\":\"V4PORTADAWIDE\",\"url\":\"media\/ver\/port\/wide\/v4\/31641\/01_091_00055949\/PORTADA-0.jpg\",\"thumb_url\":\"\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":19},{\"localizer\":\"V4PORTADAWIDEMOBILE\",\"url\":\"media\/ver\/port\/wide\/mobile\/v4\/31641\/01_092_00055950\/portada-mobile.jpg\",\"thumb_url\":\"\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel de barcelona\",\"copyright\":\"\",\"order\":20},{\"localizer\":\"V4PORTADA\",\"url\":\"media\/ver\/port\/v4\/31641\/01_090_00055951\/portada-1.jpg\",\"thumb_url\":\"\",\"title\":\"L'Oreneta - La Villarroel\",\"description\":\"l'oreneta a la villarroel de barcleona\",\"copyright\":\"\",\"order\":21},{\"localizer\":\"V4CARTELL\",\"url\":\"media\/ver\/cartell\/v4\/31641\/01_089_00056143\/cartell-web.jpg\",\"thumb_url\":\"\",\"title\":\"L'Oreneta - La villarroel\",\"description\":\"l'oreneta a la villarroel de barceloan\",\"copyright\":\"\",\"order\":22}]","material__texto_intro":"","data_material":null,"data_gallery":"","data_discounts":"[]","contract_is_open":false,"in_tour":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Oreneta - La Villarroel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/ex\\\/loreneta\\\/\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/ex\\\/loreneta\\\/\",\"name\":\"L'Oreneta - La Villarroel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/#website\"},\"datePublished\":\"2023-06-01T13:51:21+00:00\",\"dateModified\":\"2024-05-14T09:19:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/ex\\\/loreneta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/ex\\\/loreneta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/ex\\\/loreneta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espectacles\",\"item\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/ex\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;Oreneta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/\",\"name\":\"La Villarroel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/#organization\",\"name\":\"La Villarroel\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lavillarroel.cat\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/09\\\/teatre-villaroel-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.lavillarroel.cat\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2017\\\/09\\\/teatre-villaroel-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"La Villarroel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lavillarroel.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/TeatreVillarroel\",\"https:\\\/\\\/x.com\\\/la_villarroel\",\"http:\\\/\\\/instagram.com\\\/la_villarroel\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/LaVillarroel#p\\\/u\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Oreneta - La Villarroel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/","url":"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/","name":"L'Oreneta - La Villarroel","isPartOf":{"@id":"https:\/\/www.lavillarroel.cat\/es\/#website"},"datePublished":"2023-06-01T13:51:21+00:00","dateModified":"2024-05-14T09:19:18+00:00","breadcrumb":{"@id":"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lavillarroel.cat\/es\/ex\/loreneta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.lavillarroel.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Espectacles","item":"https:\/\/www.lavillarroel.cat\/es\/ex\/"},{"@type":"ListItem","position":3,"name":"L&#8217;Oreneta"}]},{"@type":"WebSite","@id":"https:\/\/www.lavillarroel.cat\/es\/#website","url":"https:\/\/www.lavillarroel.cat\/es\/","name":"La Villarroel","description":"","publisher":{"@id":"https:\/\/www.lavillarroel.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lavillarroel.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.lavillarroel.cat\/es\/#organization","name":"La Villarroel","url":"https:\/\/www.lavillarroel.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lavillarroel.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.lavillarroel.cat\/wp-content\/uploads\/sites\/5\/2017\/09\/teatre-villaroel-logo.svg","contentUrl":"https:\/\/www.lavillarroel.cat\/wp-content\/uploads\/sites\/5\/2017\/09\/teatre-villaroel-logo.svg","width":1,"height":1,"caption":"La Villarroel"},"image":{"@id":"https:\/\/www.lavillarroel.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/TeatreVillarroel","https:\/\/x.com\/la_villarroel","http:\/\/instagram.com\/la_villarroel","http:\/\/www.youtube.com\/user\/LaVillarroel#p\/u"]}]}},"translations":[{"id":3264,"locale":"ca"},{"id":3265,"locale":"es"}],"_links":{"self":[{"href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/ex\/3265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/ex"}],"about":[{"href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/types\/ex"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/comments?post=3265"}],"acf:term":[{"embeddable":true,"taxonomy":"season","href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/season\/93"}],"wp:attachment":[{"href":"https:\/\/www.lavillarroel.cat\/es\/wp-json\/wp\/v2\/media?parent=3265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}